{"id":1171,"date":"2005-10-01T11:06:09","date_gmt":"2005-10-01T10:06:09","guid":{"rendered":"http:\/\/carfree.fr\/index.php\/2005\/10\/01\/linvasion-motorisee\/"},"modified":"2025-01-07T10:16:38","modified_gmt":"2025-01-07T09:16:38","slug":"linvasion-motorisee","status":"publish","type":"post","link":"https:\/\/carfree.fr\/index.php\/2005\/10\/01\/linvasion-motorisee\/","title":{"rendered":"L&rsquo;invasion motoris\u00e9e"},"content":{"rendered":"<p>Les bagnoles, motos, 4X4, quads et autres conneries envahissent aussi la campagne et la montagne. <!--more--><\/p>\n<p>Fervent randonneur, il ne se passe pas un samedi ou un dimanche, quand je marche dans notre pourtant si belle r\u00e9gion d&rsquo;Auvergne, sans que je sois (je ne suis pas le seul) agress\u00e9 par tous ces abrutis motoris\u00e9s. Donc la campagne et la montagne sont aussi envahies par les adeptes des \u00ab\u00a0sports m\u00e9caniques\u00a0\u00bb. <\/p>\n<p>Il faut savoir que les constructeurs de ces engins inutiles filent du fric aux communes pour organiser des manifestations qui attirent malheureusement des hordes de spectateurs qui viennent baver devant ces spectacles affligeants.<\/p>\n<p>Plus grave, ils arrivent \u00e0 obtenir des d\u00e9rogations pour faire rouler leurs engins dans des zones jusque l\u00e0 prot\u00e9g\u00e9es&#8230; Encore une image du lib\u00e9ralisme triomphant. Qu&rsquo;est-ce qu&rsquo;on ne ferait pas pour le fric!<\/p>\n<p>Bon courage<br \/>\nMichel<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les bagnoles, motos, 4X4, quads et autres conneries envahissent aussi la campagne et la montagne.<\/p>\n","protected":false},"author":3,"featured_media":46189,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[52],"tags":[1848,268,244,183,520,185,103,85,736,279,521,1606],"views":5342,"_links":{"self":[{"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/posts\/1171"}],"collection":[{"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1171"}],"version-history":[{"count":0,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/posts\/1171\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/media\/46189"}],"wp:attachment":[{"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}