{"id":19443,"date":"2013-01-18T13:16:44","date_gmt":"2013-01-18T12:16:44","guid":{"rendered":"http:\/\/carfree.fr\/?p=19443"},"modified":"2016-05-25T14:27:32","modified_gmt":"2016-05-25T13:27:32","slug":"la-voiture-a-lepreuve-de-la-crise","status":"publish","type":"post","link":"https:\/\/carfree.fr\/index.php\/2013\/01\/18\/la-voiture-a-lepreuve-de-la-crise\/","title":{"rendered":"La voiture \u00e0 l&rsquo;\u00e9preuve de la crise"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" title=\"fin-de-route\" src=\"http:\/\/carfree.fr\/images\/fin-de-route.jpg\" alt=\"\" width=\"420\" height=\"200\" \/><\/p>\n<p>On ne peut pas revendiquer \u00e0 corps et \u00e0 cris moins de place pour la  voiture et ne pas tenter de faire un parall\u00e8le avec la m\u00e9vente des  voitures fran\u00e7aises. A force de contraindre l\u2019automobiliste, c\u2019est peut-\u00eatre la crise  \u00e9conomique qui va donner le coup de gr\u00e2ce \u00e0 la supr\u00e9matie de la bagnole. <!--more--><\/p>\n<p>Mais quand on d\u00e9fend un choix de vie, un choix pour se transporter, il faut aussi avoir le courage de ses convictions.<\/p>\n<p>Apr\u00e8s avoir dit \u00ab\u00a0oui, la voiture pollue\u00a0\u00bb, \u00ab\u00a0oui, la voiture occupe  trop de place en ville\u00a0\u00bb, il faut accepter les cons\u00e9quences d\u2019un recul  de ce mode de transport.<\/p>\n<p>Apr\u00e8s avoir tant id\u00e9alis\u00e9 la bagnole dans la pub, dans nos rapports \u00e0  l\u2019argent, au luxe, \u00e0 la qualit\u00e9 de vie, et jou\u00e9 sur l\u2019\u00e9motionnel de nos  inconscients, force est de reconna\u00eetre que des pans entiers de notre  soci\u00e9t\u00e9 d\u00e9couvrent effar\u00e9s que l\u2019automobile est aussi un vecteur  \u00e9conomique difficile \u00e0 contourner d\u00e8s lors que le marasme s\u2019installe.<\/p>\n<p>Encore une \u00e9pine dans le pied des vieilles d\u00e9mocraties europ\u00e9ennes  qui n\u2019ont pas encore toutes venues arriver le mauvais coup de la  d\u00e9confiture des constructeurs.<\/p>\n<p>Certes, la v\u00e9rit\u00e9 n\u2019est pas facile \u00e0 dire: dans vingt ans, on n\u2019aura  vraisemblablement plus qu\u2019un constructeur \u00a0\u00bb de r\u00e9f\u00e9rence\u00a0\u00bb en Europe  pour satisfaire le march\u00e9 int\u00e9rieur d\u2019une industrie devenue mondialis\u00e9e.<\/p>\n<p>La firme Volkswagen (la voiture du peuple) est bien plac\u00e9e pour  occuper cette place de la gamme moyenne des automobilistes \u00ab\u00a0moyens\u00a0\u00bb.<\/p>\n<p>Mais un retournement de tendance est toujours possible.<\/p>\n<p>L\u2019autre grand d\u00e9fi de nos gouvernements va \u00eatre celui de la reconversion des travailleurs de l\u2019automobile.<\/p>\n<p>Le virage ne sera pas facile \u00e0 prendre et quelques d\u00e9rapages sont \u00e0  craindre. On en voit d\u00e9j\u00e0 les pr\u00e9misses avec Peugeot et Renault qui l\u2019un  et l\u2019autre sont \u00e0 la peine.<\/p>\n<p>Trop longtemps, les fabricants se sont laiss\u00e9s berc\u00e9s par le p\u00e9trole  abondant et peu cher, sans trop se pr\u00e9occuper de l\u2019apr\u00e8s p\u00e9trole.<\/p>\n<p>Aujourd\u2019hui, on d\u00e9couvre notre retard en mati\u00e8re de transports  alternatifs : l\u2019\u00e9lectrique peine \u00e0 relever le d\u00e9fi et le choix du  transport individuel n\u2019est pas facile \u00e0 remettre en question.<\/p>\n<p>Jusqu\u2019o\u00f9 est-on capable de d\u00e9truire la plan\u00e8te?<\/p>\n<p>Apr\u00e8s l\u2019indomptable effet de serre, va t-on \u00e0 pr\u00e9sent commettre un fric-frac avec la fracturation hydraulique de nos sous-sols?<\/p>\n<p>Notre socialisme pataud montre ses limites d\u00e8s lors qu\u2019il faut  inculquer \u00e0 la population des r\u00e9flexes collectifs pour se d\u00e9placer.<\/p>\n<p><a title=\"http:\/\/velomaxou.com\" href=\"http:\/\/velomaxou.com\" target=\"_blank\">http:\/\/velomaxou.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>On ne peut pas revendiquer \u00e0 corps et \u00e0 cris moins de place pour la voiture et ne pas tenter de faire un parall\u00e8le avec la m\u00e9vente des voitures fran\u00e7aises. <a class=\"more-link\" href=\"https:\/\/carfree.fr\/index.php\/2013\/01\/18\/la-voiture-a-lepreuve-de-la-crise\/\">Lire la suite&#8230;<\/a><\/p>\n","protected":false},"author":195,"featured_media":19450,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[495,73],"tags":[85,139,169,16,393,235,396],"views":6674,"_links":{"self":[{"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/posts\/19443"}],"collection":[{"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/users\/195"}],"replies":[{"embeddable":true,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/comments?post=19443"}],"version-history":[{"count":0,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/posts\/19443\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/media?parent=19443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/categories?post=19443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/tags?post=19443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}