{"id":205,"date":"2005-11-02T16:45:00","date_gmt":"2005-11-02T15:45:00","guid":{"rendered":"http:\/\/carfree.fr\/index.php\/2005\/11\/02\/lettre-aux-automodebiles\/"},"modified":"2023-11-13T16:53:32","modified_gmt":"2023-11-13T15:53:32","slug":"lettre-aux-automodebiles","status":"publish","type":"post","link":"https:\/\/carfree.fr\/index.php\/2005\/11\/02\/lettre-aux-automodebiles\/","title":{"rendered":"Lettre aux automod\u00e9biles"},"content":{"rendered":"<p>Je suis un cycliste chevronn\u00e9, historiquement Toulousain, actuellement parisiannis\u00e9, mais sans aucune \u00e9tiquette. J\u2019ai \u00e9cris une lettre pour les automod\u00e9biles citadins, de mani\u00e8re \u00e0 essayer d\u2019\u00eatre convainquant, en mettant la priorit\u00e9 sur leur attitude face aux cyclistes. <!--more--><\/p>\n<p>Je ne pense pas que beaucoup d\u2019automobilistes seraient pr\u00eats \u00e0 changer leur tuture contre une petite reine (tant pis pour eux), et je pr\u00e9f\u00e8re donc leur demander de nous faciliter la vie.<\/p>\n<p>Bon \u00e0 la fin je leur propose quand m\u00eame le changement, mais je pense qu\u2019ils se braqueront moins avec une lettre \u201csoft\u201d.<\/p>\n<p>Mon id\u00e9e serait de distribuer cette lettre sous les pare brise, aux fen\u00eatres dans les bouchons, etc. Qu\u2019en pensez-vous? Pouvez-vous si elle vous plait la diffuser par vos moyens?<\/p>\n<p>V\u00e9lorutionairement votre<br \/>\nAntoine<\/p>\n<p><a href=\"http:\/\/carfree.fr\/lettre_aux_automodebiles.pdf\" target=\"_blank\" rel=\"noopener\">Lettre aux automod\u00e9biles (Format pdf, 10 Ko)<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Je suis un cycliste chevronn\u00e9, historiquement Toulousain, actuellement parisiannis\u00e9, mais sans aucune \u00e9tiquette. J\u2019ai \u00e9cris une lettre pour les automod\u00e9biles citadins, de mani\u00e8re \u00e0 essayer d\u2019\u00eatre convainquant, en mettant la <a class=\"more-link\" href=\"https:\/\/carfree.fr\/index.php\/2005\/11\/02\/lettre-aux-automodebiles\/\">Lire la suite&#8230;<\/a><\/p>\n","protected":false},"author":11,"featured_media":43492,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[127],"tags":[1848,181,224,106,113],"views":3925,"_links":{"self":[{"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/posts\/205"}],"collection":[{"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/comments?post=205"}],"version-history":[{"count":0,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/posts\/205\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/media\/43492"}],"wp:attachment":[{"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/media?parent=205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/categories?post=205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/tags?post=205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}