{"id":3137,"date":"2009-06-02T09:22:33","date_gmt":"2009-06-02T08:22:33","guid":{"rendered":"http:\/\/carfree.fr\/?p=3137"},"modified":"2020-08-14T13:37:06","modified_gmt":"2020-08-14T12:37:06","slug":"sortir-de-la-civilisation-de-lautomobile","status":"publish","type":"post","link":"https:\/\/carfree.fr\/index.php\/2009\/06\/02\/sortir-de-la-civilisation-de-lautomobile\/","title":{"rendered":"Sortir de la civilisation de l&rsquo;automobile"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" title=\"sortir-civilisation-automobile\" src=\"http:\/\/carfree.fr\/images\/sortir-civilisation-automobile.jpg\" alt=\"sortir-civilisation-automobile\" width=\"420\" height=\"200\" \/><\/p>\n<p>La voiture individuelle et son expansion ph\u00e9nom\u00e9nale dans la deuxi\u00e8me moiti\u00e9 du XX\u00e8 si\u00e8cle aura \u00e9t\u00e9 le le moteur d&rsquo;une croissance folle, et le symbole d&rsquo;un r\u00eave de libert\u00e9&#8230; qui a tourn\u00e9 au cauchemar. <!--more--><\/p>\n<p>Encombrement, enlaidissement urbain, r\u00e9chauffement climatique, pic p\u00e9trolier, pollution atmosph\u00e9rique, b\u00e9tonnage des paysages, endettement des m\u00e9nages, bouchons, bruit, stress, accidents&#8230; les raisons ne manquent pas pour en finir avec ce mod\u00e8le pr\u00e9dateur qui nous a men\u00e9 dans une impasse suicidaire.<\/p>\n<p>Qu&rsquo;on les estampille \u00ab\u00a0propres\u00a0\u00bb, qu&rsquo;on en change le mode de propulsion ou qu&rsquo;on r\u00e9duise leur consommation \u2013 comme l&rsquo;exige Obama \u2013 n&rsquo;y changera rien: <strong>circuler seul dans des v\u00e9hicules pr\u00e9vus pour 4, pesant plus d&rsquo;une tonne et restant immobiles 98% du temps reste fondamentalement aberrant.<\/strong><\/p>\n<p>Le parc automobile mondial atteint presque le milliard de v\u00e9hicules. La Suisse compte 500 voitures pour 1000 habitants. Si nos 6.7 milliards de semblables faisaient de m\u00eame, il faudrait donc 3 milliards de voitures. Physiquement impossible.<\/p>\n<p>C&rsquo;est donc aussi dans un souci de solidarit\u00e9 avec ces peuples du sud dont nous nous accaparons les ressources qu&rsquo;il faut mettre \u00e0 terre l&rsquo;industrie automobile, tout en exigeant la reconversion de ses travailleurs.<\/p>\n<p>Plus localement, les innombrables initiatives et r\u00e9f\u00e9rendums qui concernent la mobilit\u00e9 sont autant de luttes qui devraient nous permettre de converger vers un avenir d\u00e9barrass\u00e9 de l&rsquo;addiction automobile.<\/p>\n<p>Vite, devenons des objecteurs de bagnole!<\/p>\n<p>Thibault Schneeberger<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La voiture individuelle et son expansion ph\u00e9nom\u00e9nale dans la deuxi\u00e8me moiti\u00e9 du XX\u00e8 si\u00e8cle aura \u00e9t\u00e9 le le moteur d&rsquo;une croissance folle, et le symbole d&rsquo;un r\u00eave de libert\u00e9&#8230; qui <a class=\"more-link\" href=\"https:\/\/carfree.fr\/index.php\/2009\/06\/02\/sortir-de-la-civilisation-de-lautomobile\/\">Lire la suite&#8230;<\/a><\/p>\n","protected":false},"author":1390,"featured_media":3139,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[127,52,73,6,124],"tags":[275,416,185,130,103,129,57,188,595,81,315,272,134,610,490,347,274,287,33,1669,105,220,164,38],"views":5044,"_links":{"self":[{"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/posts\/3137"}],"collection":[{"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/users\/1390"}],"replies":[{"embeddable":true,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/comments?post=3137"}],"version-history":[{"count":0,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/posts\/3137\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/media?parent=3137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/categories?post=3137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/tags?post=3137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}