{"id":37811,"date":"2016-10-06T08:54:25","date_gmt":"2016-10-06T07:54:25","guid":{"rendered":"http:\/\/carfree.fr\/?p=37811"},"modified":"2016-12-16T11:23:59","modified_gmt":"2016-12-16T10:23:59","slug":"a-quoi-bon-construire-des-lgv-si-cest-pour-elargir-des-autoroutes","status":"publish","type":"post","link":"https:\/\/carfree.fr\/index.php\/2016\/10\/06\/a-quoi-bon-construire-des-lgv-si-cest-pour-elargir-des-autoroutes\/","title":{"rendered":"A quoi bon construire des LGV si c&rsquo;est pour \u00e9largir des autoroutes?"},"content":{"rendered":"<p>Le Pr\u00e9sident Hollande a d\u00e9clar\u00e9 sa flamme aux dirigeants du b\u00e9tonneur Vinci Autoroutes, qui appartient au m\u00eame groupe que le contractant du projet d&rsquo;a\u00e9roport de Notre-Dame des Landes et de la LGV \u00ab\u00a0L&rsquo;Oc\u00e9ane\u00a0\u00bb Tours &#8211; Bordeaux, \u00e0 l&rsquo;occasion du lancement d&rsquo;un chantier d&rsquo;\u00e9largissement autoroutier sur un axe desservi par une LGV ouverte il y a six ans. <!--more--><\/p>\n<p>Le 28 juillet dernier, le Pr\u00e9sident Hollande s&rsquo;est rendu \u00e0 Rivesaltes, dans les Pyr\u00e9n\u00e9es Orientales, pour inaugurer le chantier d&rsquo;\u00e9largissement de l&rsquo;autoroute A9 vers l&rsquo;Espagne. Il a, en pr\u00e9sence du PDG de Vinci Autoroutes, c\u00e9l\u00e9br\u00e9 les vertus de l&rsquo;autoroute A9, en pr\u00e9cisant que \u00ab [ses] travaux (&#8230;) repr\u00e9sentent un investissement de 180 millions d\u2019euros pour le groupe Vinci. L\u2019A9 est un ouvrage majeur pour la grande r\u00e9gion, son attractivit\u00e9, son rayonnement \u00bb. Il aurait pu expliquer pourquoi l&rsquo;ancienne r\u00e9gion Languedoc-Roussillon, travers\u00e9e quasiment de part en part par cette autoroute, tutoie les records de France en mati\u00e8re de pauvret\u00e9 et de ch\u00f4mage&#8230;<\/p>\n<p><strong>Viva Vinci !<\/strong><\/p>\n<p>Et, au cas o\u00f9 les choses ne seraient pas assez claires, il a fait les yeux doux \u00e0 Vinci Autoroutes (qui appartient au groupe qui doit construire et exploiter l&rsquo;a\u00e9roport de Notre-Dame des Landes, pour rappel) : \u00ab Je veux remercier les soci\u00e9t\u00e9s concessionnaires, car elles contribuent \u00e0 la s\u00e9curit\u00e9 des automobilistes. L\u2019autoroute A9 est strat\u00e9gique pour notre pays, c\u2019est la troisi\u00e8me autoroute la plus fr\u00e9quent\u00e9e de France apr\u00e8s l\u2019A7 et l\u2019A1. (\u2026) L\u2019A9 est une infrastructure europ\u00e9enne. Ici, c\u2019est l\u2019Europe \u00bb.<\/p>\n<p>L&rsquo;Europe ? Certes, mais une Europe des b\u00e9tonneurs, et il fallait cela pour plaire \u00e0 Vinci.<\/p>\n<p>Le Pr\u00e9sident s&rsquo;est fendu, comme il \u00e9tait pr\u00e9visible, d&rsquo;une envol\u00e9e \u00e9colo : \u00ab les grands ouvrages ne sont pas contraires \u00e0 la pr\u00e9servation de la biodiversit\u00e9 \u00bb. Il n&rsquo;est pas all\u00e9 jusqu&rsquo;\u00e0 dire que prendre l&rsquo;autoroute \u00e9tait plus \u00e9colo que de prendre le train, comme il l&rsquo;avait fait \u00e0 propos des autocars au d\u00e9but de l&rsquo;ann\u00e9e 2015, mais cela lui a probablement br\u00fbl\u00e9 les l\u00e8vres.<\/p>\n<p>Lanc\u00e9 \u00e0 l&rsquo;automne 2015 par le gouvernement, le plan de relance autoroutier pr\u00e9voit 3,27 milliards d&rsquo;euros d&rsquo;investissements sur trois ans, sans qu&rsquo;il en co\u00fbte au contribuable, d&rsquo;apr\u00e8s le Pr\u00e9sident. En fait, les concessionnaires lancent ce plan en \u00e9change d&rsquo;un allongement de la dur\u00e9e de leur concession, pendant laquelle l&rsquo;Etat ne pourra pas r\u00e9cup\u00e9rer l&rsquo;exploitation des autoroutes ni les recettes qui en d\u00e9coulent. Le co\u00fbt pour le contribuable prend donc la forme d&rsquo;un amoindrissement des recettes futures.<\/p>\n<p>Quant au plan d&rsquo;investissement, il n&rsquo;est pas \u00e9norme dans l&rsquo;absolu, mais il compte dans un contexte o\u00f9 l&rsquo;Etat s&rsquo;engage dans la voie d&rsquo;un d\u00e9sengagement ferroviaire sans rivage, avec un m\u00e9pris complet pour les probl\u00e8mes d&rsquo;environnement et de soci\u00e9t\u00e9 que cela pose, et dans un consensus complet parmi les partis \u00e9tablis.<\/p>\n<p><strong>La LGV entre Perpignan et Barcelone : un grand projet inutile&#8230;<\/strong><\/p>\n<p>Enfin, un d\u00e9tail concerne plus sp\u00e9cifiquement l&rsquo;axe de l&rsquo;A9 entre Perpignan et l&rsquo;Espagne \u00e0 cet endroit, et il croustille sous la dent. En 2010, les autorit\u00e9s ont inaugur\u00e9 une ligne ferroviaire parall\u00e8le \u00e0 cet axe autoroutier, la LGV Perpignan &#8211; Figueras, prolong\u00e9e jusqu&rsquo;\u00e0 Barcelone depuis. Or, le consortium priv\u00e9 qui g\u00e9rait la ligne est en redressement judiciaire, reflet du fait que la LGV transporte un trafic de marchandises faible voire r\u00e9siduel, et un trafic bien faible en voyageurs, de l&rsquo;ordre de 800 000 voyageurs par an, ce qui \u00e9quivaut \u00e0 une quinzaine de jours de trafic sur l&rsquo;A9 \u00e0 cet endroit, selon les chiffres donn\u00e9s par Vinci. Autrement dit, non seulement la LGV n&rsquo;a provoqu\u00e9 aucun report de la route vers le rail, mais l&rsquo;augmentation de la mobilit\u00e9 rend n\u00e9cessaire un \u00e9largissement de la voirie routi\u00e8re parall\u00e8le.<\/p>\n<p>Pour le dire autrement, on s&rsquo;aper\u00e7oit, quatre ans apr\u00e8s sa mise en service, que la LGV Perpignan &#8211; Figueras a \u00e9t\u00e9 un grand projet inutile. Cette notion n&rsquo;est pas qu&rsquo;un phantasme d&rsquo;\u00e9colo attard\u00e9, et peut donc s&rsquo;appliquer \u00e0 un projet ferroviaire. Le souci est qu&rsquo;une infrastructure ferroviaire n&rsquo;a de sens que si un contexte favorable accompagne son d\u00e9veloppement. Or, du point de vue du fret ferroviaire, l&rsquo;Espagne est dans une seconde division en Europe, et la France l&rsquo;y suit d&rsquo;assez pr\u00e8s ; or, une ligne ne va pas cr\u00e9er de trafic de son propre fait, si le trafic ferroviaire ne fait pas l&rsquo;objet de mesures volontaristes, compte tenu de surcro\u00eet de la stagnation \u00e9conomique que conna\u00eet l&rsquo;Europe.<\/p>\n<p><strong>&#8230; qui pr\u00e9figure le tunnel entre Lyon et Turin<\/strong><\/p>\n<p>Or, cette ligne se compare, par un certain nombre d&rsquo;aspects, au projet de tunnel entre Lyon et Turin : un massif montagneux \u00e0 franchir, un axe transfrontalier o\u00f9 les trafics ferroviaires sont minoritaires. Et les justifications de la mise en service de la LGV Perpignan &#8211; Figueras (dans le style : \u00ab\u00a0un symbole de l&rsquo;Europe unie qui doit permettre un report modal vers un mode ferroviaire non polluant\u00a0\u00bb, et blablabla), sont exactement les m\u00eames que celles des d\u00e9fenseurs du Lyon &#8211; Turin aujourd&rsquo;hui, selon un spectre qui va de certains syndicats cheminots \u00e0 l&rsquo;ensemble des partis politiques \u00e9tablis, en passant par la FNAUT. Or, les m\u00eames causes produisant les m\u00eames effets, le Lyon &#8211; Turin n&rsquo;aura sans doute aucun effet sur la circulation routi\u00e8re \u00e0 travers les Alpes, comme le Perpignan &#8211; Barcelone n&rsquo;en a eu aucun sur la circulation \u00e0 travers les Pyr\u00e9n\u00e9es. Les partisans du Lyon &#8211; Turin ne pourront pas dire que ce ph\u00e9nom\u00e8ne \u00e9tait impr\u00e9visible, puisqu&rsquo;il se sera d\u00e9j\u00e0 produit ici dans les Pyr\u00e9n\u00e9es.<\/p>\n<p>Bien cordialement,<\/p>\n<p>Vincent Doumayrou,<br \/>\nauteur de la Fracture ferroviaire, pourquoi le TGV ne sauvera pas le chemin de fer,<br \/>\nPr\u00e9face de Georges Ribeill. Les Editions de l&rsquo;Atelier, Ivry-sur-Seine, 2007.<br \/>\n<a href=\"https:\/\/blogs.mediapart.fr\/vincent-doumayrou\/blog\" target=\"_blank\">https:\/\/blogs.mediapart.fr\/vincent-doumayrou\/blog<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Pr\u00e9sident Hollande a d\u00e9clar\u00e9 sa flamme aux dirigeants du b\u00e9tonneur Vinci Autoroutes, qui appartient au m\u00eame groupe que le contractant du projet d&rsquo;a\u00e9roport de Notre-Dame des Landes et de <a class=\"more-link\" href=\"https:\/\/carfree.fr\/index.php\/2016\/10\/06\/a-quoi-bon-construire-des-lgv-si-cest-pour-elargir-des-autoroutes\/\">Lire la suite&#8230;<\/a><\/p>\n","protected":false},"author":101,"featured_media":37812,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[77,8],"tags":[1709,112,194,158,571,927,119,131,1508,824],"views":8658,"_links":{"self":[{"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/posts\/37811"}],"collection":[{"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/users\/101"}],"replies":[{"embeddable":true,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/comments?post=37811"}],"version-history":[{"count":0,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/posts\/37811\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/media\/37812"}],"wp:attachment":[{"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/media?parent=37811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/categories?post=37811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/tags?post=37811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}