{"id":44567,"date":"2022-05-31T08:17:02","date_gmt":"2022-05-31T07:17:02","guid":{"rendered":"http:\/\/carfree.fr\/?p=44567"},"modified":"2022-05-31T14:41:41","modified_gmt":"2022-05-31T13:41:41","slug":"le-probleme","status":"publish","type":"post","link":"https:\/\/carfree.fr\/index.php\/2022\/05\/31\/le-probleme\/","title":{"rendered":"Le probl\u00e8me"},"content":{"rendered":"<p>La vid\u00e9o suivante n&rsquo;est pas un clip de la s\u00e9curit\u00e9 routi\u00e8re bien trop occup\u00e9e \u00e0 culpabiliser les victimes, pi\u00e9tons ou cyclistes, face \u00e0 l&rsquo;arrogance automobile. C&rsquo;est juste une vid\u00e9o montrant la r\u00e9alit\u00e9 du principal probl\u00e8me circulant dans nos rues, \u00e0 savoir la voiture. <!--more--><\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">The Ask. <\/p>\n<p>Source footage via <a href=\"https:\/\/twitter.com\/DrJalawson?ref_src=twsrc%5Etfw\">@DrJalawson<\/a> <a href=\"https:\/\/t.co\/PmsAZg1o0v\">pic.twitter.com\/PmsAZg1o0v<\/a><\/p>\n<p>&mdash; Tom Flood (@tomflood1) <a href=\"https:\/\/twitter.com\/tomflood1\/status\/1491428576847339520?ref_src=twsrc%5Etfw\">February 9, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Traduction: Ne portez pas de v\u00eatements sombres. Ne regardez pas votre t\u00e9l\u00e9phone. N&rsquo;\u00e9coutez pas de musique. Traversez au passage pi\u00e9ton. Attendez l&rsquo;autorisation de l&rsquo;agent pour traverser le passage pi\u00e9ton. Allez-y. Nous demandons \u00e0 nos enfants de tout faire bien. Donc les automobilistes peuvent tout faire de travers. Nous pouvons pr\u00e9venir la violence routi\u00e8re. Nous choisissons juste continuellement de ne pas le faire.<\/p>\n<p>La vid\u00e9o compl\u00e8te se trouve ci-dessous et l&rsquo;officier de police ainsi que l&rsquo;\u00e9tudiante sont aujourd&rsquo;hui en bonne sant\u00e9.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">This is what hero police officers do! North East Police Officer Annette Goodyear saved a student from harm\u2019s way early this morning. <a href=\"https:\/\/t.co\/efpgjqucuO\">pic.twitter.com\/efpgjqucuO<\/a><\/p>\n<p>&mdash; Dr. Jeffrey Lawson (@DrJalawson) <a href=\"https:\/\/twitter.com\/DrJalawson\/status\/1489700948972769280?ref_src=twsrc%5Etfw\">February 4, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Source: <a href=\"https:\/\/www.creativebyrovelo.com\" rel=\"noopener\" target=\"_blank\">https:\/\/www.creativebyrovelo.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La vid\u00e9o suivante n&rsquo;est pas un clip de la s\u00e9curit\u00e9 routi\u00e8re bien trop occup\u00e9e \u00e0 culpabiliser les victimes, pi\u00e9tons ou cyclistes, face \u00e0 l&rsquo;arrogance automobile. C&rsquo;est juste une vid\u00e9o montrant <a class=\"more-link\" href=\"https:\/\/carfree.fr\/index.php\/2022\/05\/31\/le-probleme\/\">Lire la suite&#8230;<\/a><\/p>\n","protected":false},"author":37,"featured_media":44568,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4,73,1038,9],"tags":[996,135,737,101,178,648,651,144],"views":5676,"_links":{"self":[{"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/posts\/44567"}],"collection":[{"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/comments?post=44567"}],"version-history":[{"count":0,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/posts\/44567\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/media\/44568"}],"wp:attachment":[{"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/media?parent=44567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/categories?post=44567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/tags?post=44567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}