{"id":9563,"date":"2010-09-01T12:34:02","date_gmt":"2010-09-01T11:34:02","guid":{"rendered":"http:\/\/carfree.fr\/?p=9563"},"modified":"2020-08-24T11:12:17","modified_gmt":"2020-08-24T10:12:17","slug":"cest-quoi-un-velobus","status":"publish","type":"post","link":"https:\/\/carfree.fr\/index.php\/2010\/09\/01\/cest-quoi-un-velobus\/","title":{"rendered":"C&rsquo;est quoi un v\u00e9lobus ?"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" title=\"velobus\" src=\"http:\/\/carfree.fr\/images\/velobus.jpg\" alt=\"\" width=\"420\" height=\"200\" \/><\/p>\n<p>Il s\u2019agit d\u2019un ramassage scolaire \u00e0 v\u00e9lo plut\u00f4t qu\u2019en bus : des enfants (dans votre \u00e9cole, votre commune ?) se rendent \u00e0 l\u2019\u00e9cole et en reviennent le soir \u00e0 v\u00e9lo en groupe encadr\u00e9 par des adultes form\u00e9s \u00e0 cet effet. Un horaire pr\u00e9cis et des points d\u2019arr\u00eat sont d\u00e9finis, que chacun doit respecter. <!--more--><\/p>\n<p><strong>A qui \u00e7a s\u2019adresse ?<\/strong><\/p>\n<p>Tous les enfants sont susceptibles de participer d\u00e8s la 4e ann\u00e9e primaire. Une \u00e9tude de la KULeuven (Belgique) a en effet d\u00e9montr\u00e9 qu\u2019en moyenne, \u00e0 partir de 9 ans un enfant est capable de r\u00e9agir \u00e0 une situation complexe dans le trafic. Plus jeune, il vaut mieux alors \u00eatre accompagn\u00e9 d\u2019un grand fr\u00e8re, d\u2019une grande soeur ou d\u2019un parent.<\/p>\n<p>Une convention est pass\u00e9e entre enfants et adultes : chacun s\u2019engage \u00e0 respecter les r\u00e8gles \u00e9tablies pour le bon fonctionnement de l\u2019op\u00e9ration (v\u00e9lo en bon \u00e9tat, respect des horaires et du code de la route, respect mutuel\u2026).<\/p>\n<p><strong>Et la s\u00e9curit\u00e9 dans tout \u00e7a ?<\/strong><\/p>\n<p>La formation des accompagnateurs et des enfants sur le trajet du v\u00e9lobus r\u00e9duit fortement les risques : chacun conna\u00eet l\u2019itin\u00e9raire et les \u00e9ventuels endroits plus d\u00e9licats. Par ailleurs, le fait de rouler en groupe et de porter des v\u00eatements bien visibles (gilets, serre-pantalon ou autocollants r\u00e9fl\u00e9chissants, fanions, \u2026) incite instinctivement les automobilistes \u00e0 plus de prudence.<\/p>\n<p><strong>Pourquoi participer ?<\/strong><\/p>\n<p>* pour rendre le chemin vers l\u2019\u00e9cole plus vivable et plus s\u00fbr, car cela fait autant de voitures en moins, et l\u2019environnement sourit de voir (s)ces jeunes pousses respirer \u00e0 pleins poumons un air un peu moins pollu\u00e9 !<br \/>\n* pour favoriser l\u2019autonomie des enfants, leur sant\u00e9 mentale et physique (tant probl\u00e9matiques actuellement), leurs contacts sociaux ;<br \/>\n* pour permettre aux enfants d\u2019appr\u00e9hender les dangers de la route et d\u2019apprendre le trafic de fa\u00e7on active et pas sur une banquette de voiture, ce qui leur servira maintenant et plus tard ;<br \/>\n* les parents sont en outre d\u00e9charg\u00e9s de la t\u00e2che de les amener \u00e0 l\u2019\u00e9cole, sauf s\u2019ils accompagnent de temps en temps le v\u00e9lobus, ce qui est aussi bon pour leur sant\u00e9 (et vivement souhaitable pour le bon fonctionnement du projet).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il s\u2019agit d\u2019un ramassage scolaire \u00e0 v\u00e9lo plut\u00f4t qu\u2019en bus : des enfants (dans votre \u00e9cole, votre commune ?) se rendent \u00e0 l\u2019\u00e9cole et en reviennent le soir \u00e0 v\u00e9lo <a class=\"more-link\" href=\"https:\/\/carfree.fr\/index.php\/2010\/09\/01\/cest-quoi-un-velobus\/\">Lire la suite&#8230;<\/a><\/p>\n","protected":false},"author":168,"featured_media":9564,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4,8,7],"tags":[247,285,640,588,308,320,151,220,790,131,1664,113],"views":7281,"_links":{"self":[{"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/posts\/9563"}],"collection":[{"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/users\/168"}],"replies":[{"embeddable":true,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/comments?post=9563"}],"version-history":[{"count":0,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/posts\/9563\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/media?parent=9563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/categories?post=9563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/carfree.fr\/index.php\/wp-json\/wp\/v2\/tags?post=9563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}